{"id":14483,"date":"2026-04-06T20:23:55","date_gmt":"2026-04-06T18:23:55","guid":{"rendered":"https:\/\/webpreview.develon.com\/?page_id=14483"},"modified":"2026-04-07T12:33:44","modified_gmt":"2026-04-07T10:33:44","slug":"investor","status":"publish","type":"page","link":"https:\/\/www.develon.com\/en\/investor\/","title":{"rendered":"Investor"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"14483\" class=\"elementor elementor-14483\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-799fe206 elementor-section-full_width elementor-section-stretched page-title-section elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"799fe206\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                            <div class=\"elementor-background-overlay\"><\/div>\n            \n                <div class=\"elementor-container elementor-column-gap-extended\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-178b2547 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"178b2547\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-dacf085 elementor-invisible elementor-widget elementor-widget-pxl_breadcrumb\" data-id=\"dacf085\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"pxl_breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-breadcrumb-wrap\">\r\n\t<ul class=\"pxl-breadcrumb\"><li><span class=\"breadcrumb-entry\">Home<\/span><\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32d0c840 elementor-absolute pxl-rain-drop-height elementor-widget elementor-widget-pxl_rain_drop\" data-id=\"32d0c840\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"pxl_rain_drop.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-rain-drop style-2\">\r\n            <div class=\"pxl-rain-drop-item\"><\/div>\r\n            <div class=\"pxl-rain-drop-item\"><\/div>\r\n            <div class=\"pxl-rain-drop-item\"><\/div>\r\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-210315a6 elementor-widget elementor-widget-pxl_heading\" data-id=\"210315a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-210315a6-5689\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h1 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tInvestor\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h1>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5f5f1c elementor-widget elementor-widget-spacer\" data-id=\"d5f5f1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c5974 elementor-widget elementor-widget-pxl_heading\" data-id=\"b8c5974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-b8c5974-4969\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h2 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tDevelon Group is an ecosystem of innovation, growth, and strategic value. Investing in Develon Group means accessing a unique network of skills, methodologies, and operational assets, where strategy, technology, and execution work together to generate real and sustainable growth.\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h2>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11d010b elementor-align-left elementor-widget elementor-widget-pxl_button\" data-id=\"11d010b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-11d010b-1723\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n    <a href=\"\/en\/contact-us\/\" class=\"btn pxl-icon-active btn-block-inline  btn-default pxl-icon--left\">\r\n                    <span class=\"pxl--btn-icon\">\r\n                <i aria-hidden=\"true\" class=\"fal fa-hands-helping\"><\/i>                            <\/span>\r\n                <span class=\"pxl--btn-text\" data-text=\"Prenota un incontro\">\r\n            Book a meeting        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ecd6bd elementor-widget elementor-widget-spacer\" data-id=\"5ecd6bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-487cf91 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"487cf91\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06a2cff elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"06a2cff\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_widescreen&quot;:&quot;fadeInUp&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-29ec3c4 elementor-widget elementor-widget-spacer\" data-id=\"29ec3c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-791eb951 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"791eb951\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-457b81cc pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"457b81cc\" data-element_type=\"column\" data-e-type=\"column\" id=\"features\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-2dae1f53 elementor-widget elementor-widget-pxl_heading\" data-id=\"2dae1f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-2dae1f53-8979\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tWe build long-term value through expertise, method, and vision.\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-565359b3 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"565359b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p>Investing in Develon means entering a structured ecosystem, where innovation, expertise, and strategy unite to create sustainable and scalable value.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68eebfe5 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none elementor-invisible\" data-id=\"68eebfe5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-54402aed col-feature-landing pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"54402aed\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-c1806e1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c1806e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fal fa-check\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-386ea7aa heading-feature-landing elementor-widget elementor-widget-pxl_heading\" data-id=\"386ea7aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-386ea7aa-6738\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tStrategic Innovation\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f8e9c7c elementor-widget elementor-widget-pxl_text_editor\" data-id=\"2f8e9c7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner\" >\r\n\t\t<p data-start=\"515\" data-end=\"759\">Every project stems from in-depth analysis and long-term vision. We apply established methodologies to identify high-impact opportunities, developing proprietary solutions that distinctively combine technology and market.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-857d5a7 col-feature-landing pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"857d5a7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-9cd26fe elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9cd26fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fal fa-check\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e59cdf heading-feature-landing elementor-widget elementor-widget-pxl_heading\" data-id=\"0e59cdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-0e59cdf-3863\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tEfficient Execution\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c78730a elementor-widget elementor-widget-pxl_text_editor\" data-id=\"c78730a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner\" >\r\n\t\t<p data-start=\"797\" data-end=\"1073\">Our approach integrates operational and decision-making expertise, ensuring that every initiative is implemented with precision, constantly monitored, and geared towards concrete results. Investing in Develon means focusing on rigorous execution and measurable performance.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4930bd3 col-feature-landing pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"4930bd3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:300,&quot;background_background&quot;:&quot;classic&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-b06d1fb elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b06d1fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fal fa-check\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e9ea3f heading-feature-landing elementor-widget elementor-widget-pxl_heading\" data-id=\"3e9ea3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-3e9ea3f-8620\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tScalable growth\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8f0bcad elementor-widget elementor-widget-pxl_text_editor\" data-id=\"8f0bcad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner\" >\r\n\t\t<p data-start=\"1111\" data-end=\"1359\">We create replicable structures and models that allow projects to grow stably and sustainably. Scalability is designed in from the outset, with clear roadmaps, defined KPIs, and strategies for multiplying the value generated over time.<\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-96611fa e-flex e-con-boxed e-con e-parent\" data-id=\"96611fa\" data-element_type=\"container\" data-e-type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t\t\t<div class=\"elementor-element elementor-element-de4878b elementor-widget elementor-widget-spacer\" data-id=\"de4878b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d5e303 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"6d5e303\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4a4e16 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"c4a4e16\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n        <div class=\"elementor-widget-wrap\">\r\n                     \r\n                    <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9c081b4 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"9c081b4\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-07ad8ba elementor-widget elementor-widget-pxl_heading\" data-id=\"07ad8ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-07ad8ba-7303\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\t\t\t\t<span class=\"pxl-item--subtext\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"\">THE GROUP<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tExperience and continuity\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f04b69 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"9f04b69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p><span style=\"font-weight: 400\"><strong>Our evolution is based on continuity, method, and constant development of structure and processes.<\/strong> <\/span><\/p><p><span style=\"font-weight: 400\">Develon Group was born from a progressive growth journey, built over time by professionals with solid backgrounds and consolidated expertise.<\/span><\/p><p><span style=\"font-weight: 400\">We are an organisation designed for stable and sustainable growth.<\/span><\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f6c729 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"1f6c729\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0642812 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"0642812\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n        <div class=\"elementor-widget-wrap\">\r\n                     \r\n                    <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-05fea3e pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"05fea3e\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-8f6c5cc elementor-widget elementor-widget-pxl_heading\" data-id=\"8f6c5cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-8f6c5cc-6451\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\t\t\t\t<span class=\"pxl-item--subtext\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"\">PEOPLE<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tProven skills\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a35543 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"4a35543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p><strong>Our core value is people.<\/strong><\/p><p><span style=\"font-weight: 400\">The team combines expertise in strategy, operations, technology, and business development. Each member contributes vertical experience and execution capability.<\/span><\/p><p><span style=\"font-weight: 400\">We combine vision and pragmatism, transforming ideas into structured projects and measurable results.<\/span><\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-99077f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"99077f3\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52394af elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"52394af\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n        <div class=\"elementor-widget-wrap\">\r\n                     \r\n                    <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c8628a pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"1c8628a\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-480de49 elementor-widget elementor-widget-pxl_heading\" data-id=\"480de49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-480de49-4277\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\t\t\t\t<span class=\"pxl-item--subtext\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"\">Vision<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tScalable growth\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96621d9 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"96621d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p><strong>Our aim is to sustainably develop value in the areas where we operate.<\/strong><\/p><p><span style=\"font-weight: 400\">We are following a clear roadmap, focused on scalable opportunities and building a strong long-term position. The strategy is defined, disciplined, and focused on structured expansion.<\/span><\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b57030 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"1b57030\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-938ed79 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"938ed79\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\r\n        <div class=\"elementor-widget-wrap\">\r\n                     \r\n                    <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-62315c5 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"62315c5\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-0b7306d elementor-widget elementor-widget-pxl_heading\" data-id=\"0b7306d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-0b7306d-5160\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\t\t\t<div class=\"pxl-item--subtitle px-sub-title-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\t\t\t\t<span class=\"pxl-item--subtext\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"\">THE MODEL<\/span>\r\n\t\t\t\t<\/span>\r\n\t\t\t<\/div>\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tValue creation\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a7ebbd elementor-widget elementor-widget-pxl_text_editor\" data-id=\"9a7ebbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p><strong>Our model is clear and transparent, based on efficiency, Specialisation and strategic positioning.<\/strong><\/p><p><span style=\"font-weight: 400\">The structure is designed to generate recurring value, optimise resources, and support the scalable development of initiatives.<\/span><\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-35954341 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"35954341\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4023d9a9 pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"4023d9a9\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-40d1f634 elementor-section-full_width elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"40d1f634\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a43284 elementor-hidden-tablet elementor-hidden-mobile pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"a43284\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-1f076d5 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"1f076d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.develon.com\/wp-content\/uploads\/2026\/04\/develon_cover-600x600.jpeg\" class=\"attachment-safebyte-portfolio size-safebyte-portfolio wp-image-14565\" alt=\"\" srcset=\"https:\/\/www.develon.com\/wp-content\/uploads\/2026\/04\/develon_cover-600x600.jpeg 600w, https:\/\/www.develon.com\/wp-content\/uploads\/2026\/04\/develon_cover-150x150.jpeg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f022ae3 pxl-column-none pxl-column-overflow-hidden-no elementor-invisible\" data-id=\"f022ae3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-d9e9a56 elementor-widget elementor-widget-pxl_heading\" data-id=\"d9e9a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\r\n<div id=\"pxl-pxl_heading-d9e9a56-4920\" class=\"pxl-heading px-sub-title-default-style\">\r\n\t<div class=\"pxl-heading--inner\">\r\n\t\t\r\n\t\t<h3 class=\"pxl-item--title style-default highlight-default wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n\r\n\t\t\t<span class=\"pxl-heading--text\">\r\n\r\n\t\t\t\t\t\t\t\t\tInvest in Develon Group\t\r\n\t\t\t\t\t\r\n\r\n\t\t\t<\/span>\r\n\t\t<\/h3>\r\n\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364f5ed elementor-widget elementor-widget-pxl_text_editor\" data-id=\"364f5ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor highlight-gradient\">\r\n\t<div class=\"pxl-item--inner wow PXLfadeInUp\" data-wow-delay=\"300ms\">\r\n\t\t<p><span style=\"font-weight: 400\">Investing in Develon means participating in the development of our proprietary projects. Our approach is transparent, disciplined, and focused on creating sustainable value.<\/span><\/p><p><strong>Every project:<\/strong><\/p><ul><li><span style=\"font-weight: 400\">It arises from a strategic analysis<\/span><\/li><li><span style=\"font-weight: 400\">It is led by a dedicated team<\/span><\/li><li><span style=\"font-weight: 400\">Here is a defined roadmap<\/span><\/li><li><span style=\"font-weight: 400\">It has measurable goals<\/span><\/li><li><span style=\"font-weight: 400\">It is designed for scalability<\/span><\/li><\/ul><p><span style=\"font-weight: 400\"><strong>Request an initial introductory meeting to better understand the opportunities you can find at Develon.<\/strong><\/span><\/p>\t\t\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9016c9b elementor-align-left elementor-widget__width-auto elementor-widget elementor-widget-pxl_button\" data-id=\"9016c9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_button-9016c9b-2638\" class=\"pxl-button pxl-atc-link wow PXLfadeInUp\" data-wow-delay=\"ms\">\r\n    <a href=\"\/en\/contact-us\/\" class=\"btn pxl-icon-active btn-block-inline  btn-default pxl-icon--left\">\r\n                    <span class=\"pxl--btn-icon\">\r\n                <i aria-hidden=\"true\" class=\"far fa-hands-helping\"><\/i>                            <\/span>\r\n                <span class=\"pxl--btn-text\" data-text=\"Diventa Investor\">\r\n            Become an Investor        <\/span>\r\n    <\/a>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Home Investor Develon Group \u00e8 un ecosistema di innovazione, crescita e valore strategico. Investire in Develon Group significa accedere a un network unico di competenze, metodologie e asset operativi, dove strategia, tecnologia e execution lavorano insieme per generare crescita reale e sostenibile. Prenota un incontro Costruiamo valore nel lungo periodo attraverso competenza, metodo e visione [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-14483","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/pages\/14483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/comments?post=14483"}],"version-history":[{"count":22,"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/pages\/14483\/revisions"}],"predecessor-version":[{"id":14813,"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/pages\/14483\/revisions\/14813"}],"wp:attachment":[{"href":"https:\/\/www.develon.com\/en\/wp-json\/wp\/v2\/media?parent=14483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}